			{"id":238808,"date":"2021-11-30T12:33:00","date_gmt":"2021-11-30T17:33:00","guid":{"rendered":"https:\/\/fsc-ccf.ca\/?post_type=research&#038;p=238808"},"modified":"2026-05-08T16:38:03","modified_gmt":"2026-05-08T20:38:03","slug":"secteur-forestier-saskatchewan","status":"publish","type":"research","link":"https:\/\/fsc-ccf.ca\/fr\/recherche\/secteur-forestier-saskatchewan\/","title":{"rendered":"Le secteur forestier de la Saskatchewan : comp\u00e9tences futures pour une revitalisation dirig\u00e9e par les Autochtones"},"content":{"rendered":"\n<p>Le secteur forestier du nord de la Saskatchewan doit faire face \u00e0 des p\u00e9nuries de main-d&#8217;\u0153uvre, \u00e0 des lacunes en mati\u00e8re de comp\u00e9tences et au d\u00e9sir des communaut\u00e9s autochtones d&#8217;\u00e9largir le secteur vers des produits forestiers renouvelables et alternatifs.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Faits marquants du document<\/h2>\n\n\n\n<p>Les communaut\u00e9s autochtones ont acquis un pouvoir \u00e9conomique consid\u00e9rable dans le secteur forestier de la Saskatchewan en soutenant une formation cibl\u00e9e pour les membres de la communaut\u00e9 tout au long de la cha\u00eene de valeur foresti\u00e8re. Pour maintenir ce pouvoir, il faudra plus d&#8217;Autochtones occupant des postes dans l&#8217;ensemble du secteur, y compris des emplois hautement qualifi\u00e9s.<\/p>\n\n\n\n<p>Cependant, de nombreux jeunes travailleurs ne sont pas int\u00e9ress\u00e9s \u00e0 entrer dans l&#8217;industrie, et les r\u00e9cents progr\u00e8s technologiques en foresterie ont rendu l&#8217;acc\u00e8s \u00e0 une formation de niveau sup\u00e9rieur encore plus essentiel. Les communaut\u00e9s autochtones sont \u00e9galement ambivalentes quant aux effets de la foresterie conventionnelle sur l&#8217;environnement et les modes de vie traditionnels. L&#8217;incorporation de produits forestiers alternatifs et r\u00e9g\u00e9n\u00e9ratifs est une solution potentielle.<\/p>\n\n\n\n<p>Pour r\u00e9soudre tous ces probl\u00e8mes, les divers acteurs de l&#8217;\u00e9cosyst\u00e8me de d\u00e9veloppement des comp\u00e9tences du nord de la Saskatchewan, y compris les fournisseurs d&#8217;\u00e9ducation, les gouvernements, l&#8217;industrie et les apprenants, doivent se coordonner pour cr\u00e9er les opportunit\u00e9s de formation n\u00e9cessaires pour faire \u00e9voluer le secteur dans l&#8217;avenir.<\/p>\n\n\n<div id=\"buttons-block-block_613a138e5af79\" class=\"buttons-block \">\n    <ul class=\"buttons-block__buttons\">\n                                    <li class=\"buttons-block__item button-item section-title button-item--button\">\n                    <a class=\"btn btn--download btn-dark\" href=\"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/Rapport-CCF_le-secteur-forestier-de-la-saskatchewan_fr.pdf\" download>Le secteur forestier de la Saskatchewan : comp\u00e9tences futures pour une revitalisation dirig\u00e9e par les Autochtones <span class=\"filesize\">PDF 2.04 MB<\/span><\/a>\n                <\/li>\n                        <\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-ob-blocks-content-cards has-numbers\">\n<div class=\"wp-block-ob-blocks-content-card wp-block-ob-blocks-content-card--title\"><h3 class=\"numbered-card__title\" style=\"color:#000000\">Le\u00e7ons tir\u00e9es<\/h3><div class=\"numbered-card__text\" style=\"color:#4e0047\"><\/div><div class=\"numbered-card__background\" style=\"background-color:#4e0047\"><\/div><div class=\"numbered-card__number\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-ob-blocks-content-card\"><h3 class=\"numbered-card__title\" style=\"color:#4e0047\"><\/h3><div class=\"numbered-card__text\" style=\"color:#000000\"><p>Les communaut\u00e9s autochtones ont acquis un pouvoir \u00e9conomique consid\u00e9rable dans le secteur forestier de la Saskatchewan en favorisant la formation cibl\u00e9e de leurs membres \u00e0 chaque maillon de la cha\u00eene de valeur foresti\u00e8re. Pour maintenir ce pouvoir, davantage d&#8217;Autochtones devront occuper des emplois dans tout le secteur, y compris parmi les professions plus sp\u00e9cialis\u00e9es.<\/p><\/div><div class=\"numbered-card__background\" style=\"background-color:#4e0047\"><\/div><div class=\"numbered-card__number\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-ob-blocks-content-card\"><h3 class=\"numbered-card__title\" style=\"color:#4e0047\"><\/h3><div class=\"numbered-card__text\" style=\"color:#000000\"><p>Les communaut\u00e9s autochtones des r\u00e9gions foresti\u00e8res de la Saskatchewan sont tiraill\u00e9es entre les occasions d\u2019emploi locales bien r\u00e9mun\u00e9r\u00e9es offertes dans le secteur forestier et les craintes li\u00e9es \u00e0 l&#8217;\u00e9rosion de leurs modes de vie traditionnels sur le territoire et \u00e0 la d\u00e9gradation environnementale.<\/p><\/div><div class=\"numbered-card__background\" style=\"background-color:#4e0047\"><\/div><div class=\"numbered-card__number\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-ob-blocks-content-card\"><h3 class=\"numbered-card__title\" style=\"color:#4e0047\"><\/h3><div class=\"numbered-card__text\" style=\"color:#000000\"><p>Utiliser diff\u00e9remment les for\u00eats, par l\u2019agro-foresterie ou le d\u00e9veloppement de produits non ligneux, est l\u2019une des fa\u00e7ons de soutenir le d\u00e9veloppement du secteur forestier autochtone dans cette province. Pour actualiser ce potentiel dans les communaut\u00e9s locales, les fournisseurs de services \u00e9ducatifs doivent permettre aux apprenants d\u2019acqu\u00e9rir des connaissances dans les domaines de l\u2019\u00e9cologie, des sciences de l&#8217;environnement et de la gestion des affaires.<\/p><\/div><div class=\"numbered-card__background\" style=\"background-color:#4e0047\"><\/div><div class=\"numbered-card__number\"><\/div><\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le secteur forestier du nord de la Saskatchewan doit faire face \u00e0 des p\u00e9nuries de main-d&#8217;\u0153uvre, \u00e0 des lacunes en mati\u00e8re de comp\u00e9tences et au d\u00e9sir des communaut\u00e9s autochtones d&#8217;\u00e9largir le secteur vers des produits forestiers renouvelables et alternatifs.<\/p>\n","protected":false},"menu_order":0,"template":"","tags":[228,1581,1296,1361,574],"region":[150],"research_type":[],"populations":[1639,1640],"themes":[1633,1656,1556],"class_list":["post-238808","research","type-research","status-publish","hentry","tag-autochtones","tag-indigenous-populations-fr","tag-northern-fr","tag-saskatchewan-fr","tag-secteur-forestier","region-saskatchewan-fr","populations-rural-remote-northern-communities-fr","populations-mid-career-workers-fr","themes-formation-professionnelle","themes-skilled-trades","themes-secteurs"],"acf":{"hero_image":{"ID":238801,"id":238801,"title":"pexels-karolina-grabowska-4206118","filename":"pexels-karolina-grabowska-4206118-scaled.jpg","filesize":503391,"url":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-scaled.jpg","link":"https:\/\/fsc-ccf.ca\/fr\/recherche\/secteur-forestier-saskatchewan\/pexels-karolina-grabowska-4206118-2\/","alt":"","author":"16","description":"","caption":"","name":"pexels-karolina-grabowska-4206118-2","status":"inherit","uploaded_to":238808,"date":"2021-11-30 16:51:31","modified":"2021-11-30 16:51:31","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/fsc-ccf.ca\/wp-includes\/images\/media\/default.png","width":2048,"height":1365,"sizes":{"thumbnail":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365,"preview":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-10x7.jpg","preview-width":10,"preview-height":7,"content-card-thumbnail":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-800x600.jpg","content-card-thumbnail-width":800,"content-card-thumbnail-height":600,"slider-image":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-1600x1200.jpg","slider-image-width":1600,"slider-image-height":1200,"hero-image":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-2000x1333.jpg","hero-image-width":2000,"hero-image-height":1333,"inline-image":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-1024x512.jpg","inline-image-width":1024,"inline-image-height":512,"content-card-thumbnail-vertical":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-400x600.jpg","content-card-thumbnail-vertical-width":400,"content-card-thumbnail-vertical-height":600}},"slider_image":false,"external_linkout":[],"scorecard_content":false,"authors":"<p>Publi\u00e9 le 30 november 30 2021<\/p>\n<p>Auteures: Erin Macpherson, Jane Cooper<\/p>\n","authors_colour":["grey"],"show_post_date":[],"report":true,"file_upload":{"ID":238809,"id":238809,"title":"Le secteur forestier de la Saskatchewan : comp\u00e9tences futures pour une revitalisation dirig\u00e9e par les Autochtones","filename":"Rapport-CCF_le-secteur-forestier-de-la-saskatchewan_fr.pdf","filesize":2134358,"url":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/Rapport-CCF_le-secteur-forestier-de-la-saskatchewan_fr.pdf","link":"https:\/\/fsc-ccf.ca\/fr\/recherche\/secteur-forestier-saskatchewan\/rapport-ccf_le-secteur-forestier-de-la-saskatchewan_fr\/","alt":"","author":"16","description":"Le secteur forestier du nord de la Saskatchewan doit faire face \u00e0 des p\u00e9nuries de main-d'\u0153uvre, \u00e0 des lacunes en mati\u00e8re de comp\u00e9tences et au d\u00e9sir des communaut\u00e9s autochtones d'\u00e9largir le secteur vers des produits forestiers renouvelables et alternatifs.","caption":"","name":"rapport-ccf_le-secteur-forestier-de-la-saskatchewan_fr","status":"inherit","uploaded_to":238808,"date":"2021-11-30 17:22:04","modified":"2022-07-14 15:48:04","menu_order":0,"mime_type":"application\/pdf","type":"application","subtype":"pdf","icon":"https:\/\/fsc-ccf.ca\/wp-includes\/images\/media\/document.png"},"report_sort_name":"Le secteur forestier de la Saskatchewan : comp\u00e9tences futures pour une revitalisation dirig\u00e9e par les Autochtones","contributors":"","file_secondary_tags":false,"report_image":false,"report_link":"","reports_rows":{"report":false},"investment":"0","source":"","thumbnail_image":{"ID":238801,"id":238801,"title":"pexels-karolina-grabowska-4206118","filename":"pexels-karolina-grabowska-4206118-scaled.jpg","filesize":503391,"url":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-scaled.jpg","link":"https:\/\/fsc-ccf.ca\/fr\/recherche\/secteur-forestier-saskatchewan\/pexels-karolina-grabowska-4206118-2\/","alt":"","author":"16","description":"","caption":"","name":"pexels-karolina-grabowska-4206118-2","status":"inherit","uploaded_to":238808,"date":"2021-11-30 16:51:31","modified":"2021-11-30 16:51:31","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/fsc-ccf.ca\/wp-includes\/images\/media\/default.png","width":2048,"height":1365,"sizes":{"thumbnail":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365,"preview":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-10x7.jpg","preview-width":10,"preview-height":7,"content-card-thumbnail":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-800x600.jpg","content-card-thumbnail-width":800,"content-card-thumbnail-height":600,"slider-image":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-1600x1200.jpg","slider-image-width":1600,"slider-image-height":1200,"hero-image":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-2000x1333.jpg","hero-image-width":2000,"hero-image-height":1333,"inline-image":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-1024x512.jpg","inline-image-width":1024,"inline-image-height":512,"content-card-thumbnail-vertical":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2021\/11\/pexels-karolina-grabowska-4206118-400x600.jpg","content-card-thumbnail-vertical-width":400,"content-card-thumbnail-vertical-height":600}},"partners":[{"ID":4416,"post_author":"25","post_date":"2019-07-17 21:21:59","post_date_gmt":"2019-07-18 01:21:59","post_content":"<!-- wp:paragraph -->\n<p><a href=\"https:\/\/www.signal49.ca\/\" target=\"_blank\" rel=\"noreferrer noopener\">Signal49 Recherche<\/a> est le plus important organisme ind\u00e9pendant et sans but lucratif de recherche appliqu\u00e9e au pays. Depuis plus de 60\u00a0ans, il rassemble des gens et des id\u00e9es de toutes les disciplines et de tous les secteurs d\u2019activit\u00e9 en vue de r\u00e9soudre des probl\u00e8mes complexes. Gr\u00e2ce \u00e0 sa recherche r\u00e9put\u00e9e sur les tendances \u00e9conomiques, les politiques publiques et l\u2019excellence organisationnelle, ainsi qu\u2019\u00e0 ses relations uniques, Signal49 habilite et inspire les dirigeants \u00e0 \u00e9difier un avenir meilleur pour tous les Canadiens.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Signal49 Recherche tirera profit de sa capacit\u00e9 de recherche appliqu\u00e9e, de ses communications et de son expertise en organisation, ainsi que de son vaste r\u00e9seau pancanadien de partenaires, pour diriger les activit\u00e9s de mise en commun et de transmission des connaissances du Centre et contribuer \u00e0 son programme de recherche. Ces activit\u00e9s aideront les Canadiens et Canadiennes \u00e0 prendre des d\u00e9cisions relativement \u00e0 la formation, permettront de cr\u00e9er des prototypes et de mettre \u00e0 l\u2019essai de nouvelles approches pour d\u00e9terminer les comp\u00e9tences les plus recherch\u00e9es, et faciliteront la diffusion publique et \u00e0 grande \u00e9chelle des renseignements et des donn\u00e9es probantes sur les pratiques exemplaires et les solutions gagnantes. La contribution au programme de recherche comprend neuf projets de recherche pluriannuels dans trois secteurs de connaissances.<\/p>\n<!-- \/wp:paragraph -->","post_title":"Signal49 Recherche","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"the-conference-board-of-canada","to_ping":"","pinged":"","post_modified":"2026-01-27 15:37:34","post_modified_gmt":"2026-01-27 20:37:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/fscccf.alphabureau.ca\/partner\/the-conference-board-of-canada\/","menu_order":1,"post_type":"partner","post_mime_type":"","comment_count":"0","filter":"raw"}]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le secteur forestier de la Saskatchewan : comp\u00e9tences futures pour une revitalisation dirig\u00e9e par les Autochtones - Future Skills Centre \u2022 Centre des Comp\u00e9tences futures<\/title>\n<meta name=\"description\" content=\"Le secteur forestier du nord de la Saskatchewan doit faire face \u00e0 des p\u00e9nuries de main-d&#039;\u0153uvre, \u00e0 des lacunes en mati\u00e8re de comp\u00e9tences et au d\u00e9sir des communaut\u00e9s autochtones d&#039;\u00e9largir le secteur vers des produits forestiers renouvelables et alternatifs.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fsc-ccf.ca\/fr\/recherche\/secteur-forestier-saskatchewan\/\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fsc-ccf.ca\\\/fr\\\/recherche\\\/secteur-forestier-saskatchewan\\\/\",\"url\":\"https:\\\/\\\/fsc-ccf.ca\\\/fr\\\/recherche\\\/secteur-forestier-saskatchewan\\\/\",\"name\":\"Le secteur forestier de la Saskatchewan : comp\u00e9tences futures pour une revitalisation dirig\u00e9e par les Autochtones - Future Skills Centre \u2022 Centre des Comp\u00e9tences futures\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fsc-ccf.ca\\\/fr\\\/#website\"},\"datePublished\":\"2021-11-30T17:33:00+00:00\",\"dateModified\":\"2026-05-08T20:38:03+00:00\",\"description\":\"Le secteur forestier du nord de la Saskatchewan doit faire face \u00e0 des p\u00e9nuries de main-d'\u0153uvre, \u00e0 des lacunes en mati\u00e8re de comp\u00e9tences et au d\u00e9sir des communaut\u00e9s autochtones d'\u00e9largir le secteur vers des produits forestiers renouvelables et alternatifs.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fsc-ccf.ca\\\/fr\\\/recherche\\\/secteur-forestier-saskatchewan\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fsc-ccf.ca\\\/fr\\\/recherche\\\/secteur-forestier-saskatchewan\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fsc-ccf.ca\\\/fr\\\/recherche\\\/secteur-forestier-saskatchewan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fsc-ccf.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recherche\",\"item\":\"https:\\\/\\\/fsc-ccf.ca\\\/fr\\\/recherche\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le secteur forestier de la Saskatchewan : comp\u00e9tences futures pour une revitalisation dirig\u00e9e par les Autochtones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fsc-ccf.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/fsc-ccf.ca\\\/fr\\\/\",\"name\":\"Future Skills Centre \u2022 Centre des Comp\u00e9tences futures\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fsc-ccf.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fsc-ccf.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fsc-ccf.ca\\\/fr\\\/#organization\",\"name\":\"Future Skills Centre \u2022 Centre des Comp\u00e9tences futures\",\"url\":\"https:\\\/\\\/fsc-ccf.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/fsc-ccf.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fsc-ccf.ca\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/FSC_logo_colour_rgb_positive_ENG.png\",\"contentUrl\":\"https:\\\/\\\/fsc-ccf.ca\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/FSC_logo_colour_rgb_positive_ENG.png\",\"width\":618,\"height\":528,\"caption\":\"Future Skills Centre \u2022 Centre des Comp\u00e9tences futures\"},\"image\":{\"@id\":\"https:\\\/\\\/fsc-ccf.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/2161871137193201\\\/\",\"https:\\\/\\\/x.com\\\/fsc_ccf_en\",\"https:\\\/\\\/www.instagram.com\\\/fsc_ccf\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fsc-ccf\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le secteur forestier de la Saskatchewan : comp\u00e9tences futures pour une revitalisation dirig\u00e9e par les Autochtones - Future Skills Centre \u2022 Centre des Comp\u00e9tences futures","description":"Le secteur forestier du nord de la Saskatchewan doit faire face \u00e0 des p\u00e9nuries de main-d'\u0153uvre, \u00e0 des lacunes en mati\u00e8re de comp\u00e9tences et au d\u00e9sir des communaut\u00e9s autochtones d'\u00e9largir le secteur vers des produits forestiers renouvelables et alternatifs.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fsc-ccf.ca\/fr\/recherche\/secteur-forestier-saskatchewan\/","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fsc-ccf.ca\/fr\/recherche\/secteur-forestier-saskatchewan\/","url":"https:\/\/fsc-ccf.ca\/fr\/recherche\/secteur-forestier-saskatchewan\/","name":"Le secteur forestier de la Saskatchewan : comp\u00e9tences futures pour une revitalisation dirig\u00e9e par les Autochtones - Future Skills Centre \u2022 Centre des Comp\u00e9tences futures","isPartOf":{"@id":"https:\/\/fsc-ccf.ca\/fr\/#website"},"datePublished":"2021-11-30T17:33:00+00:00","dateModified":"2026-05-08T20:38:03+00:00","description":"Le secteur forestier du nord de la Saskatchewan doit faire face \u00e0 des p\u00e9nuries de main-d'\u0153uvre, \u00e0 des lacunes en mati\u00e8re de comp\u00e9tences et au d\u00e9sir des communaut\u00e9s autochtones d'\u00e9largir le secteur vers des produits forestiers renouvelables et alternatifs.","breadcrumb":{"@id":"https:\/\/fsc-ccf.ca\/fr\/recherche\/secteur-forestier-saskatchewan\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fsc-ccf.ca\/fr\/recherche\/secteur-forestier-saskatchewan\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fsc-ccf.ca\/fr\/recherche\/secteur-forestier-saskatchewan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fsc-ccf.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Recherche","item":"https:\/\/fsc-ccf.ca\/fr\/recherche\/"},{"@type":"ListItem","position":3,"name":"Le secteur forestier de la Saskatchewan : comp\u00e9tences futures pour une revitalisation dirig\u00e9e par les Autochtones"}]},{"@type":"WebSite","@id":"https:\/\/fsc-ccf.ca\/fr\/#website","url":"https:\/\/fsc-ccf.ca\/fr\/","name":"Future Skills Centre \u2022 Centre des Comp\u00e9tences futures","description":"","publisher":{"@id":"https:\/\/fsc-ccf.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fsc-ccf.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/fsc-ccf.ca\/fr\/#organization","name":"Future Skills Centre \u2022 Centre des Comp\u00e9tences futures","url":"https:\/\/fsc-ccf.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/fsc-ccf.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2019\/08\/FSC_logo_colour_rgb_positive_ENG.png","contentUrl":"https:\/\/fsc-ccf.ca\/wp-content\/uploads\/2019\/08\/FSC_logo_colour_rgb_positive_ENG.png","width":618,"height":528,"caption":"Future Skills Centre \u2022 Centre des Comp\u00e9tences futures"},"image":{"@id":"https:\/\/fsc-ccf.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/2161871137193201\/","https:\/\/x.com\/fsc_ccf_en","https:\/\/www.instagram.com\/fsc_ccf\/","https:\/\/www.linkedin.com\/company\/fsc-ccf\/"]}]}},"_links":{"self":[{"href":"https:\/\/fsc-ccf.ca\/fr\/wp-json\/wp\/v2\/research\/238808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fsc-ccf.ca\/fr\/wp-json\/wp\/v2\/research"}],"about":[{"href":"https:\/\/fsc-ccf.ca\/fr\/wp-json\/wp\/v2\/types\/research"}],"version-history":[{"count":16,"href":"https:\/\/fsc-ccf.ca\/fr\/wp-json\/wp\/v2\/research\/238808\/revisions"}],"predecessor-version":[{"id":249164,"href":"https:\/\/fsc-ccf.ca\/fr\/wp-json\/wp\/v2\/research\/238808\/revisions\/249164"}],"wp:attachment":[{"href":"https:\/\/fsc-ccf.ca\/fr\/wp-json\/wp\/v2\/media?parent=238808"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fsc-ccf.ca\/fr\/wp-json\/wp\/v2\/tags?post=238808"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/fsc-ccf.ca\/fr\/wp-json\/wp\/v2\/region?post=238808"},{"taxonomy":"research_type","embeddable":true,"href":"https:\/\/fsc-ccf.ca\/fr\/wp-json\/wp\/v2\/research_type?post=238808"},{"taxonomy":"populations","embeddable":true,"href":"https:\/\/fsc-ccf.ca\/fr\/wp-json\/wp\/v2\/populations?post=238808"},{"taxonomy":"themes","embeddable":true,"href":"https:\/\/fsc-ccf.ca\/fr\/wp-json\/wp\/v2\/themes?post=238808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}